{"id":252,"date":"2023-07-27T12:19:41","date_gmt":"2023-07-27T10:19:41","guid":{"rendered":"https:\/\/www.joseconsulting.com\/evento\/annual-summaries-tax-forms-180-190-and-193\/"},"modified":"2024-01-18T15:18:36","modified_gmt":"2024-01-18T14:18:36","slug":"modelos-180-190-y-193-resumenes-anuales","status":"publish","type":"mec-events","link":"https:\/\/www.joseconsulting.com\/es\/evento\/modelos-180-190-y-193-resumenes-anuales\/","title":{"rendered":"Modelos 180, 190 y 193. Res\u00famenes anuales."},"content":{"rendered":"<p>Esta es la \u00faltima fecha del mes de Enero con obligaciones fiscales.<br \/>\nTres impuestos anuales informativos son los que se tienen que presentar como m\u00e1ximo el 31 de Enero (*)<\/p>\n<p>\u2022 <strong>Modelo 180<\/strong>. Declaraci\u00f3n anual informativa de IRPF de arrendamientos de inmuebles. Aut\u00f3nomos y empresas.<\/p>\n<p>El modelo 180 se utiliza exclusivamente para informar de los n\u00fameros que figuran en las facturas de alquiler de inmuebles urbanos recibidas en el \u00faltimo ejercicio.<\/p>\n<p>Hay que rellenar los datos del arrendador (nombre o raz\u00f3n social, NIF, provincia), los datos econ\u00f3micos de las operaciones (total de bases imponibles y retenciones pagadas a Hacienda en los Modelos 115), y por \u00faltimo, un apartado adicional con los datos del inmueble: direcci\u00f3n completa y referencia catastral (si la tiene).<\/p>\n<p>\u2022 <strong>Modelo 190<\/strong>. Declaraci\u00f3n anual informativa de IRPF de trabajadores y profesionales. Aut\u00f3nomos y empresas.<\/p>\n<p>En este modelo se detallan todos los datos de los salarios anuales de los trabajadores (salario base, pagos de IRPF, deducciones de Seguridad Social), que posteriormente Hacienda publicar\u00e1 en el perfil de cada persona como informaci\u00f3n para realizar la Declaraci\u00f3n de la Renta. Tambi\u00e9n se tiene que indicar en este modelo los salarios recibidos por los administradores de la empresa.<\/p>\n<p>El otro tipo de informaci\u00f3n que se incluye en el Modelo 190 es la relativa a las facturas recibidas de profesionales con retenci\u00f3n, generalmente aut\u00f3nomos pero tambi\u00e9n pueden ser empresas. Se tiene que detallar el total de bases imponibles y el total de IRPF ingresado en los modelos 111 para cada profesional.<\/p>\n<p>\u2022 <strong>Modelo 193<\/strong>. Declaraci\u00f3n anual informativa de IRPF. Aut\u00f3nomos y empresas.<\/p>\n<p>Este modelo tiene dos funciones informativas muy diferenciadas:<br \/>\n1) Los datos anuales de las facturas de alquiler de negocios con retenci\u00f3n.<br \/>\n2) Los datos anuales de los dividendos repartidos entre los socios de la empresa.<\/p>\n<p>En ambos casos hay que rellenar pr\u00e1cticamente la misma informaci\u00f3n. Nombre o raz\u00f3n social, NIF, provincia, y total de bases imponibles y retenciones pagadas a Hacienda en los Modelo 123 del a\u00f1o anterior.<\/p>\n<p>(*) Si el 31 de enero coincide con un s\u00e1bado\/domingo, la fecha de presentaci\u00f3n m\u00e1xima ser\u00eda el siguiente lunes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta es la \u00faltima fecha del mes de Enero con obligaciones fiscales. Tres impuestos anuales informativos son los que se tienen que presentar como m\u00e1ximo el 31 de Enero (*) \u2022 Modelo 180. Declaraci\u00f3n anual informativa de IRPF de arrendamientos de inmuebles. Aut\u00f3nomos y empresas. El modelo 180 se utiliza exclusivamente para informar de los [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","tags":[],"mec_category":[],"class_list":["post-252","mec-events","type-mec-events","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Modelos 180, 190 y 193. Res\u00famenes anuales. - Jose Consulting<\/title>\n<meta name=\"description\" content=\"El d\u00eda 31 de Enero finaliza el plazo para la presentaci\u00f3n de los siguientes modelos anuales: Modelo 180, 190 y 193.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joseconsulting.com\/es\/evento\/resumenes-anuales-modelos-180-190-y-193\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Modelos 180, 190 y 193. Res\u00famenes anuales. - Jose Consulting\" \/>\n<meta property=\"og:description\" content=\"El d\u00eda 31 de Enero finaliza el plazo para la presentaci\u00f3n de los siguientes modelos anuales: Modelo 180, 190 y 193.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.joseconsulting.com\/es\/evento\/resumenes-anuales-modelos-180-190-y-193\/\" \/>\n<meta property=\"og:site_name\" content=\"Jose Consulting\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-18T14:18:36+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.joseconsulting.com\/es\/evento\/modelos-180-190-y-193-resumenes-anuales\/\",\"url\":\"https:\/\/www.joseconsulting.com\/es\/evento\/resumenes-anuales-modelos-180-190-y-193\/\",\"name\":\"Modelos 180, 190 y 193. Res\u00famenes anuales. - Jose Consulting\",\"isPartOf\":{\"@id\":\"https:\/\/www.joseconsulting.com\/#website\"},\"datePublished\":\"2023-07-27T10:19:41+00:00\",\"dateModified\":\"2024-01-18T14:18:36+00:00\",\"description\":\"El d\u00eda 31 de Enero finaliza el plazo para la presentaci\u00f3n de los siguientes modelos anuales: Modelo 180, 190 y 193.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.joseconsulting.com\/es\/evento\/resumenes-anuales-modelos-180-190-y-193\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.joseconsulting.com\/es\/evento\/resumenes-anuales-modelos-180-190-y-193\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.joseconsulting.com\/es\/evento\/resumenes-anuales-modelos-180-190-y-193\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.joseconsulting.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\/\/www.joseconsulting.com\/evento\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Modelos 180, 190 y 193. Res\u00famenes anuales.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.joseconsulting.com\/#website\",\"url\":\"https:\/\/www.joseconsulting.com\/\",\"name\":\"Jose consulting\",\"description\":\"Asesor fiscal y contable\",\"publisher\":{\"@id\":\"https:\/\/www.joseconsulting.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.joseconsulting.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.joseconsulting.com\/#organization\",\"name\":\"Jose consulting\",\"url\":\"https:\/\/www.joseconsulting.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.joseconsulting.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.joseconsulting.com\/wp-content\/uploads\/2023\/07\/Jose-Consulting-1.png\",\"contentUrl\":\"https:\/\/www.joseconsulting.com\/wp-content\/uploads\/2023\/07\/Jose-Consulting-1.png\",\"width\":342,\"height\":102,\"caption\":\"Jose consulting\"},\"image\":{\"@id\":\"https:\/\/www.joseconsulting.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/in\/jose-manuel-garcia-ribas-21812bab\/\",\"https:\/\/www.upwork.com\/freelancers\/~01e2a8f901c002a520\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Modelos 180, 190 y 193. Res\u00famenes anuales. - Jose Consulting","description":"El d\u00eda 31 de Enero finaliza el plazo para la presentaci\u00f3n de los siguientes modelos anuales: Modelo 180, 190 y 193.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joseconsulting.com\/es\/evento\/resumenes-anuales-modelos-180-190-y-193\/","og_locale":"es_ES","og_type":"article","og_title":"Modelos 180, 190 y 193. Res\u00famenes anuales. - Jose Consulting","og_description":"El d\u00eda 31 de Enero finaliza el plazo para la presentaci\u00f3n de los siguientes modelos anuales: Modelo 180, 190 y 193.","og_url":"https:\/\/www.joseconsulting.com\/es\/evento\/resumenes-anuales-modelos-180-190-y-193\/","og_site_name":"Jose Consulting","article_modified_time":"2024-01-18T14:18:36+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.joseconsulting.com\/es\/evento\/modelos-180-190-y-193-resumenes-anuales\/","url":"https:\/\/www.joseconsulting.com\/es\/evento\/resumenes-anuales-modelos-180-190-y-193\/","name":"Modelos 180, 190 y 193. Res\u00famenes anuales. - Jose Consulting","isPartOf":{"@id":"https:\/\/www.joseconsulting.com\/#website"},"datePublished":"2023-07-27T10:19:41+00:00","dateModified":"2024-01-18T14:18:36+00:00","description":"El d\u00eda 31 de Enero finaliza el plazo para la presentaci\u00f3n de los siguientes modelos anuales: Modelo 180, 190 y 193.","breadcrumb":{"@id":"https:\/\/www.joseconsulting.com\/es\/evento\/resumenes-anuales-modelos-180-190-y-193\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.joseconsulting.com\/es\/evento\/resumenes-anuales-modelos-180-190-y-193\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.joseconsulting.com\/es\/evento\/resumenes-anuales-modelos-180-190-y-193\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.joseconsulting.com\/es\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/www.joseconsulting.com\/evento\/"},{"@type":"ListItem","position":3,"name":"Modelos 180, 190 y 193. Res\u00famenes anuales."}]},{"@type":"WebSite","@id":"https:\/\/www.joseconsulting.com\/#website","url":"https:\/\/www.joseconsulting.com\/","name":"Jose consulting","description":"Asesor fiscal y contable","publisher":{"@id":"https:\/\/www.joseconsulting.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joseconsulting.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.joseconsulting.com\/#organization","name":"Jose consulting","url":"https:\/\/www.joseconsulting.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.joseconsulting.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.joseconsulting.com\/wp-content\/uploads\/2023\/07\/Jose-Consulting-1.png","contentUrl":"https:\/\/www.joseconsulting.com\/wp-content\/uploads\/2023\/07\/Jose-Consulting-1.png","width":342,"height":102,"caption":"Jose consulting"},"image":{"@id":"https:\/\/www.joseconsulting.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/in\/jose-manuel-garcia-ribas-21812bab\/","https:\/\/www.upwork.com\/freelancers\/~01e2a8f901c002a520"]}]}},"_links":{"self":[{"href":"https:\/\/www.joseconsulting.com\/es\/wp-json\/wp\/v2\/mec-events\/252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.joseconsulting.com\/es\/wp-json\/wp\/v2\/mec-events"}],"about":[{"href":"https:\/\/www.joseconsulting.com\/es\/wp-json\/wp\/v2\/types\/mec-events"}],"author":[{"embeddable":true,"href":"https:\/\/www.joseconsulting.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.joseconsulting.com\/es\/wp-json\/wp\/v2\/comments?post=252"}],"wp:attachment":[{"href":"https:\/\/www.joseconsulting.com\/es\/wp-json\/wp\/v2\/media?parent=252"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.joseconsulting.com\/es\/wp-json\/wp\/v2\/tags?post=252"},{"taxonomy":"mec_category","embeddable":true,"href":"https:\/\/www.joseconsulting.com\/es\/wp-json\/wp\/v2\/mec_category?post=252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}